{"id":6360,"date":"2020-11-06T15:27:00","date_gmt":"2020-11-06T20:27:00","guid":{"rendered":"http:\/\/www.iftp.org\/?p=6360"},"modified":"2021-10-25T09:58:37","modified_gmt":"2021-10-25T13:58:37","slug":"marie-de-magdala-va-trouver-mes-freres-et-dis-leur-jai-vu-le-seigneur-et-voici-ce-quil-ma-dit","status":"publish","type":"post","link":"https:\/\/www.iftp.org\/index.php\/2020\/11\/06\/marie-de-magdala-va-trouver-mes-freres-et-dis-leur-jai-vu-le-seigneur-et-voici-ce-quil-ma-dit\/","title":{"rendered":"Marie de Magdala, va trouver mes fr\u00e8res et dis-leur \u2026 \u00ab j&rsquo;ai vu le Seigneur et voici ce qu&rsquo;il m&rsquo;a dit \u00bb."},"content":{"rendered":"\n<h3><strong><span class=\"has-inline-color has-vivid-cyan-blue-color\">\u00c9vangile de Jean 20, 18<\/span><\/strong><\/h3>\n\n\n\n<p class=\"has-normal-font-size\"><strong>\u0152uvre cr\u00e9\u00e9e sp\u00e9cialement pour le 10e anniversaire de la fondation de l&rsquo;Institut de formation th\u00e9ologique et pastorale par Magdalie Nadeau, accompagnatrice spirituelle selon Saint-Ignace et iconographe contemporaine Jonqui\u00e8re, Qu\u00e9bec<\/strong>.<\/p>\n\n\n\n<p class=\"has-text-align-center has-normal-font-size\">\u0152uvre d\u2019art sacr\u00e9<\/p>\n\n\n\n<p class=\"has-text-align-center has-normal-font-size\">Ic\u00f4ne religieuse contemporaine<\/p>\n\n\n\n<p class=\"has-text-align-center has-normal-font-size\">Variation d&rsquo;une ic\u00f4ne byzantine du Christ Pantocrator<\/p>\n\n\n\n<p class=\"has-text-align-center has-normal-font-size\">Ic\u00f4ne fabriqu\u00e9e avec les pages m\u00eames d&rsquo;une Bible de J\u00e9rusalem.<\/p>\n\n\n\n<p class=\"has-normal-font-size\"><strong><em>\u00ab Tu es b\u00e9ni, Dieu de la Cr\u00e9ation, Toi qui me donnes ces pages, ces feuilles, fruit de l\u2019arbre et du travail des humains.<\/em> <em>Je te les pr\u00e9sente, elles deviendront nourriture pour la vie int\u00e9rieure. \u00bb<\/em><\/strong><\/p>\n\n\n\n<ul><li><strong>Les pages bibliques de la Gen\u00e8se forment le fond de la toile.<\/strong><\/li><li><strong>Le visage du Christ est form\u00e9 avec des pages de l&rsquo;\u00e9vangile de Marc et son corps avec celles de l\u2019\u00e9vangile &nbsp;de Matthieu.<\/strong><\/li><li><strong>Le corps de Marie de Magdala est cr\u00e9\u00e9 avec les pages bibliques de l&rsquo;apparition.<\/strong><\/li><li><strong>Les rayons en relief sont form\u00e9s avec les pages du livret \u00ab\u00a0Prions en \u00c9glise\u00a0\u00bb de P\u00e2ques 2004.<\/strong><\/li><li><strong>Le Christ tient dans sa main une Bible des moines de Maredsous de 1953 r\u00e9cup\u00e9r\u00e9e \u00e0 la biblioth\u00e8que de l&rsquo;institut.<\/strong><\/li><li><strong>Ajouts de gravures de revues, image d&rsquo;un tombeau de Palestine, de sable de Charlevoix et de feuilles d&rsquo;or de 23 carats.<\/strong><\/li><li><strong>Les teintes sont obtenues avec des pigments de terre d&rsquo;ocre et du charbon.<\/strong><\/li><\/ul>\n\n\n\n<p class=\"has-text-align-center has-normal-font-size\"><strong>La symbolique dans l&rsquo;ic\u00f4ne de l&rsquo;artiste Magdalie Nadeau<\/strong><\/p>\n\n\n\n<p><strong><u>___________________________________________________________<\/u><\/strong><\/p>\n\n\n\n<p class=\"has-normal-font-size\"><strong>Se mettre en route pour en conna\u00eetre davantage sur la th\u00e9ologie\u2026<\/strong> <strong>Tout cela part d&rsquo;un d\u00e9sir \u00e9prouv\u00e9.<\/strong> <strong>Une qu\u00eate d\u00e9pos\u00e9e par Dieu lui-m\u00eame pour le chercher.<\/strong> <strong>Un \u00e9lan, qui na\u00eet souvent d&rsquo;une rencontre avec le Vivant au c\u0153ur de sa vie.<\/strong><\/p>\n\n\n\n<p class=\"has-normal-font-size\"><strong>Et comme Marie de Magdala au tombeau,<\/strong> <strong>partir en ayant soi-m\u00eame go\u00fbt\u00e9 un peu de l&rsquo;exp\u00e9rience du Ressuscit\u00e9.<\/strong> <strong>\u00catre attir\u00e9 par la Parole de Dieu, celle de la Bible et celle qui parle en son c\u0153ur.<\/strong> <strong>\u00catre invit\u00e9 alors \u00e0 faire l&rsquo;exp\u00e9rience de la Parole \u00abvivante\u00bb au coeur de la Parole-\u00e9crite.<\/strong><\/p>\n\n\n\n<p class=\"has-normal-font-size\"><strong>Le Ressuscit\u00e9 invite \u00e0 faire la rencontre d&rsquo;un Dieu br\u00fblant d&rsquo;Amour,<\/strong> <strong>d\u00e9sirant communiquer sa Vie, son feu. Le feu br\u00fble alors le c\u0153ur.<\/strong> <strong>Cette chaleur conduit le communiquer aux autres, pour un monde meilleur.<\/strong><\/p>\n\n\n\n<p><strong><u>_______________________________________________________________<\/u><\/strong><\/p>\n\n\n\n<p class=\"has-normal-font-size\">Les symboles, la mati\u00e8re et les pages bibliques se marient en cette \u0153uvre afin d&rsquo;\u00eatre un reflet du Verbe fait chair et de sa r\u00e9surrection.&nbsp; Ic\u00f4ne symbolisant l&rsquo;Incarnation de la Parole de Dieu dans la mati\u00e8re.&nbsp; L&rsquo;\u00e9tat m\u00e9ditatif de l&rsquo;artiste et la pri\u00e8re habitent toutes les \u00e9tapes du processus de cr\u00e9ation. Dans le proc\u00e9d\u00e9 de l&rsquo;ic\u00f4ne ici, c&rsquo;est la<strong> logique de l&rsquo;Incarnation<\/strong> qui donne le sens aux \u00e9tapes de cr\u00e9ation: sur le panneau de bois, au d\u00e9but, ce sont les pages bibliques qui sont fa\u00e7onn\u00e9es et coll\u00e9es, suivi des gravures et des pigments de terre d&rsquo;ocre et pour terminer avec les pigments fonc\u00e9s et du charbon.&nbsp; Processus inspir\u00e9 du passage de la Parole qui se fait chair: des pages bibliques originales jusqu&rsquo;aux pigments de terre, de l&rsquo;originel \u00e0 la mati\u00e8re. Ainsi, la base, le <strong>fond du tableau<\/strong> est fait avec les pages bibliques de la Gen\u00e8se, suivi de pages du livret \u00ab\u00a0Prions en \u00c9glise\u00a0\u00bb de P\u00e2ques 2004 qui forment des rayons en relief rayonnant du c\u0153ur du Christ.<\/p>\n\n\n\n<p class=\"has-normal-font-size\">Dans l&rsquo;ic\u00f4ne, la symbolique pr\u00e9sente une<strong> th\u00e9ologie christocentrique<\/strong>. Le Ressuscit\u00e9 invite Marie de Magdala, ainsi que toute personne, \u00e0 faire sa rencontre et d\u2019aller l&rsquo;annonce. Le Christ, par son <strong>bras droit<\/strong>, invite \u00e0 aller communiquer cette Bonne Nouvelle de vie aux <strong>autres<\/strong>, ceux-ci personnifi\u00e9s par les <strong>gravures en haut \u00e0 gauche<\/strong>.&nbsp; Il tient de son autre main le <strong>livre de la Parole<\/strong> de Dieu avec un c\u0153ur en relief sur la page de l&rsquo;apparition \u00e0 Marie de Magdala. Ce c\u0153ur \u00e9voquant l&rsquo;\u00c9vangile comme la rencontre d&rsquo;un Dieu Amour et que l&rsquo;Amour est plus fort que la mort. Le personnage de <strong>Marie de Magdala<\/strong>, qui repr\u00e9sente toute personne, est fa\u00e7onn\u00e9 avec les pages de l&rsquo;apparition en l&rsquo;\u00e9vangile de Jean. Le <strong>visage du Christ<\/strong> est form\u00e9 avec les pages de l&rsquo;\u00e9vangile de Marc et <strong>son corps<\/strong> avec les pages de l\u2019\u00e9vangile de Matthieu.<\/p>\n\n\n\n<p class=\"has-normal-font-size\">La pr\u00e9sence des <strong>feuilles d&rsquo;or<\/strong> d\u00e9pos\u00e9es sur les plis du manteau du Christ est signe de la divinit\u00e9 glorieuse du Ressuscit\u00e9. Une touche de cet or est appliqu\u00e9e sous le feu int\u00e9rieur de Marie de Magdala, ayant fait la rencontre du Ressuscit\u00e9.<\/p>\n\n\n\n<p class=\"has-normal-font-size\">De plus, la symbolique suit une <strong>d\u00e9limitation des espaces<\/strong>.&nbsp; Voulant s&rsquo;accorder sur l&rsquo;orientation que le bras <strong>droit <\/strong>du Christ prend, pointant un <strong>futur<\/strong> \u00e0 suivre, ce c\u00f4t\u00e9 du tableau repr\u00e9sente l&rsquo;avenir.&nbsp; Ainsi le <strong>c\u00f4t\u00e9 droit<\/strong> du tableau d\u00e9signe le <strong>pass\u00e9.<\/strong>&nbsp; Ensuite, la r\u00e9gion <strong>en bas<\/strong> du tableau symbolise les <strong>t\u00e9n\u00e8bres<\/strong> et la r\u00e9gion vers le <strong>haut<\/strong>, une mont\u00e9e vers la <strong>lumi\u00e8re<\/strong>.<\/p>\n\n\n\n<p class=\"has-normal-font-size\">Pour la <strong>r\u00e9gion au centre<\/strong> du tableau, plusieurs gravures \u00e9voquent le processus de mort-r\u00e9surrection. En bas de la toile, une image d&rsquo;un <strong>tombeau palestinien<\/strong> avec sa pierre ronde parle de l&rsquo;exp\u00e9rience de Marie de Magdala au tombeau et de la descente du Christ dans la mort. Ce tombeau, c&rsquo;est aussi l&rsquo;exp\u00e9rience des t\u00e9n\u00e8bres int\u00e9rieures que chacun peut faire, lieu o\u00f9 le Christ d\u00e9sire se faire Lumi\u00e8re.&nbsp; L&rsquo;ajout des <strong>pigments noirs de charbon<\/strong> donne la symbolique du passage des <strong>t\u00e9n\u00e8bres \u00e0 la lumi\u00e8re<\/strong>, de bas en haut.<\/p>\n\n\n\n<p class=\"has-normal-font-size\">La disposition des <strong>diff\u00e9rentes gravures<\/strong> suit la logique du <strong>pass\u00e9 \u00e0 droite et du futur \u00e0 gauche.<\/strong><\/p>\n\n\n\n<p class=\"has-normal-font-size\">Les gravures sont cach\u00e9es par les pigments de <strong>terre d&rsquo;ocre<\/strong> signifiant une Vie cach\u00e9e \u00e0 premi\u00e8re vue et qui demande un second regard. Une gravure des <strong>disciples<\/strong> du temps de J\u00e9sus est en parall\u00e8le \u00e0 celle des disciples d&rsquo;aujourd&rsquo;hui, une <strong>ville<\/strong> palestinienne au temps de J\u00e9sus avec, \u00e0 c\u00f4t\u00e9, une ville contemporaine. Diff\u00e9rentes images figurent la communication de la Parole et de la vie du Ressuscit\u00e9: la transmission de la lumi\u00e8re (deux <strong>lampions<\/strong> o\u00f9 un allume l&rsquo;autre), l&rsquo;enseignement (une salle de classe), la vie d&rsquo;\u00e9glise en petits groupes (des <strong>gens<\/strong> assis en cercles)\u2026<\/p>\n\n\n\n<p class=\"has-normal-font-size\">Ic\u00f4ne et \u00e9crit explicatif : <strong>Magdalie Nadeau, artiste<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9vangile de Jean 20, 18 \u0152uvre cr\u00e9\u00e9e sp\u00e9cialement pour le 10e anniversaire de la fondation de l&rsquo;Institut de formation th\u00e9ologique et pastorale par Magdalie Nadeau, accompagnatrice spirituelle selon Saint-Ignace et iconographe contemporaine Jonqui\u00e8re, Qu\u00e9bec. \u0152uvre d\u2019art sacr\u00e9 Ic\u00f4ne religieuse contemporaine Variation d&rsquo;une ic\u00f4ne byzantine du Christ Pantocrator Ic\u00f4ne fabriqu\u00e9e avec les pages m\u00eames d&rsquo;une Bible [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":6331,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.iftp.org\/index.php\/wp-json\/wp\/v2\/posts\/6360"}],"collection":[{"href":"https:\/\/www.iftp.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.iftp.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.iftp.org\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.iftp.org\/index.php\/wp-json\/wp\/v2\/comments?post=6360"}],"version-history":[{"count":12,"href":"https:\/\/www.iftp.org\/index.php\/wp-json\/wp\/v2\/posts\/6360\/revisions"}],"predecessor-version":[{"id":15639,"href":"https:\/\/www.iftp.org\/index.php\/wp-json\/wp\/v2\/posts\/6360\/revisions\/15639"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.iftp.org\/index.php\/wp-json\/wp\/v2\/media\/6331"}],"wp:attachment":[{"href":"https:\/\/www.iftp.org\/index.php\/wp-json\/wp\/v2\/media?parent=6360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.iftp.org\/index.php\/wp-json\/wp\/v2\/categories?post=6360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.iftp.org\/index.php\/wp-json\/wp\/v2\/tags?post=6360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}